{"id":5783,"date":"2022-06-09T20:44:23","date_gmt":"2022-06-09T18:44:23","guid":{"rendered":"https:\/\/www.kunstberatung.de\/newsletter\/?p=5783"},"modified":"2022-07-15T16:51:41","modified_gmt":"2022-07-15T14:51:41","slug":"mutletter-638-kunst-im-treppenhaus","status":"publish","type":"post","link":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/","title":{"rendered":"eva muellers visionary sunday post 638 &#8211; kunst im treppenhaus"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<td>M\u00f6gen Sie Sichtbeton? Kommt darauf an, meinen Sie? Als architektonisches Gestaltungsmerkmal hat es in den letzten Jahren an Bedeutung gewonnen. Die Schalungshaut, also die Oberfl\u00e4che der Holzelemente, in die der Beton gegossen wird, ist entscheidend f\u00fcr das Erscheinungsbild der Wand.<\/p>\n<p>Wir sind eher regelm\u00e4ssig glatte Wandoberfl\u00e4chen gew\u00f6hnt. Einheitliche Farbe. Ohne Kerbungen, Vertiefungen, Spuren. Beim Sichtbeton ist das ganz anders. Da sieht man ja gerade die Herstellungsmerkmale. Je feiner und individueller die Schalungselemente, desto regelm\u00e4ssiger das Ergebnis. Sogar die Ankerstellen und Anordnung der Schalungsemente lassen sich nach gestalterischen Merkmalen planen. Oder eben nicht. Weil man es rauer m\u00f6chte.<\/p>\n<p>Als Vorzeigeobjekt hat die Volksbank Breisgau-Markgr\u00e4flerland eG. nun im neuen Breisacher Gewerbegebiet ein erstes B\u00fcrogeb\u00e4ude erstellt. Ein zweites wird folgen und mit dem ersten zusammen durch die einander zugeneigte Form eine Art Tor bilden. Im Treppenhaus: Sichtbeton.<\/p>\n<p>F\u00fcr die unterschiedlichen Nutzer:innen \u2013 und deren Sichtweisen \u2013 durfte ich im Namen des Bauherrn ein Kunstkonzept f\u00fcrs Treppenhaus entwickeln. Vorstand J\u00f6rg Dehler und Gesch\u00e4ftsf\u00fchrer der Immobiliengesellschaft Christoph Greiner haben sich daf\u00fcr eingesetzt. Eine ehrenvolle Sache. Weil hier ein echter Mehrwert finanziert wird, anstatt nur m\u00f6glichst viel von den Mieter:innen erwirtschaften zu wollen.<\/p>\n<p>Weil der Sichtbeton so pr\u00e4gend ist, darf man dieses Konzept nat\u00fcrlich nicht brechen. Es brauchte also Kunst, die geometrisch streng den vorgegebenen Weg weiterverfolgt. Und trotzdem sch\u00f6ne Akzentpunkte setzt. Mit den Werken von Anna Thorwest, einer der grossen Meisterinnen der konkreten Kunst, konnte ich die verschiedenen Ebenen passend gestalten.<\/p>\n<p>Die Mieter:innen sind begeistert. Wahrscheinlich w\u00fcrden sie sich diese Kunstwerke nicht selbst kaufen. Aber an diesem Ort, so platziert und inszeniert entstand ein stimmiger Gesamteindruck. Und darauf kommt es in meiner Arbeit an. Man kann nie den Geschmack aller Leute treffen. Aber wenn die Werke mit dem jeweiligen Raum harmonieren, dann sind alle einverstanden.<\/p>\n<p>Mit frohen Sonntagsgr\u00fcssen<br \/>\nIhre Eva Mueller<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive aligncenter\" src=\"https:\/\/i2.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwesteingang.133142.jpg\" width=\"700\" height=\"570\" \/><\/div>\n<div align=\"center\"><\/div>\n<div style=\"text-align: center\" align=\"center\"><span style=\"color: #000000\">Abb: Collage von Anna Thorwest im B\u00fcrogeb\u00e4ude der Volksbank Breisgau Markgr\u00e4flerland eG in Breisach<\/span><\/div>\n<div align=\"center\"><\/div>\n<div align=\"center\"><\/div>\n<div align=\"center\"><\/div>\n<div align=\"center\">\n<div align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive aligncenter\" src=\"https:\/\/i3.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwestpicasso.133202.jpg\" width=\"700\" height=\"933\" \/><\/div>\n<p style=\"text-align: center\"><span style=\"color: #000000\">Abb.: Foto von Anna Thorwest, als Pablo Picasso 1958\u00a0 ihre Ausstellung in der Galerie Au Seuil Etroit Paris besuchte, so k\u00f6nnen sich die Mieter und Besucher des Hauses einen kleinen Einblick in die Vita der K\u00fcnstlerin verschaffen &#8211; und ihre Bedeutung.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: left\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive aligncenter\" src=\"https:\/\/i4.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwestundfahrrad.133232.jpg\" width=\"700\" height=\"825\" \/><\/div>\n<p style=\"text-align: center\"><span style=\"color: #000000\">Abb.: Collage von Anna Thorwest im Treppenhaus, B\u00fcrogeb\u00e4ude Bauherr Volksbank Markgr\u00e4flerland eG.<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #000000\">Das Bild ist so stark, dass es sogar dem Fahrrad eines Mieters standhalten kann &#8211; so sieht das eben im Alltag in Treppenh\u00e4usern manchmal aus!<\/span><\/p>\n<\/div>\n<div style=\"text-align: center\" align=\"center\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>M\u00f6gen Sie Sichtbeton? Kommt darauf an, meinen Sie? Als architektonisches Gestaltungsmerkmal hat es in den letzten Jahren an Bedeutung gewonnen. Die Schalungshaut, also die Oberfl\u00e4che der Holzelemente, in die der Beton gegossen wird, ist entscheidend f\u00fcr das Erscheinungsbild der Wand. Wir sind eher regelm\u00e4ssig glatte Wandoberfl\u00e4chen gew\u00f6hnt. Einheitliche Farbe. Ohne Kerbungen, Vertiefungen, Spuren. Beim Sichtbeton [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5783","post","type-post","status-publish","format-standard","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kunst Im Treppenhaus - Eva Mueller Kunstberatung<\/title>\n<meta name=\"description\" content=\"Die Kunstberaterin Eva Mueller hat ein Treppenhaus f\u00fcr die neuen Mieter im Gewerbegebiet in Breisach mit Kunst von Anna Thorwest gestaltet\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kunst im Treppenhaus - Eva Mueller Kunstberatung\" \/>\n<meta property=\"og:description\" content=\"Die Kunstberaterin Eva Mueller hat ein Treppenhaus f\u00fcr die neuen Mieter im Gewerbegebiet in Breisach mit Kunst von Anna Thorwest gestaltet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/\" \/>\n<meta property=\"og:site_name\" content=\"Eva Muellers Visionary Sunday Post\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-09T18:44:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T14:51:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwesteingang.133142.jpg\" \/>\n<meta name=\"author\" content=\"Eva Mueller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eva Mueller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/\"},\"author\":{\"name\":\"Eva Mueller\",\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/#\\\/schema\\\/person\\\/5956216e01d75d6ee2e332111165db0a\"},\"headline\":\"eva muellers visionary sunday post 638 &#8211; kunst im treppenhaus\",\"datePublished\":\"2022-06-09T18:44:23+00:00\",\"dateModified\":\"2022-07-15T14:51:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/\"},\"wordCount\":430,\"image\":{\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i2.createsend1.com\\\/ei\\\/r\\\/19\\\/E85\\\/556\\\/csimport\\\/thorwesteingang.133142.jpg\",\"articleSection\":[\"Newsletter Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/\",\"url\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/\",\"name\":\"Kunst im Treppenhaus - Eva Mueller Kunstberatung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i2.createsend1.com\\\/ei\\\/r\\\/19\\\/E85\\\/556\\\/csimport\\\/thorwesteingang.133142.jpg\",\"datePublished\":\"2022-06-09T18:44:23+00:00\",\"dateModified\":\"2022-07-15T14:51:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/#\\\/schema\\\/person\\\/5956216e01d75d6ee2e332111165db0a\"},\"description\":\"Die Kunstberaterin Eva Mueller hat ein Treppenhaus f\u00fcr die neuen Mieter im Gewerbegebiet in Breisach mit Kunst von Anna Thorwest gestaltet\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/blog\\\/mutletter-638-kunst-im-treppenhaus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i2.createsend1.com\\\/ei\\\/r\\\/19\\\/E85\\\/556\\\/csimport\\\/thorwesteingang.133142.jpg\",\"contentUrl\":\"https:\\\/\\\/i2.createsend1.com\\\/ei\\\/r\\\/19\\\/E85\\\/556\\\/csimport\\\/thorwesteingang.133142.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/#website\",\"url\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/\",\"name\":\"Eva Muellers Visionary Sunday Post\",\"description\":\"Eva Mueller Kunstberatung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kunstberatung.de\\\/newsletter\\\/#\\\/schema\\\/person\\\/5956216e01d75d6ee2e332111165db0a\",\"name\":\"Eva Mueller\",\"sameAs\":[\"https:\\\/\\\/www.kunstberatung.de\",\"https:\\\/\\\/de.linkedin.com\\\/in\\\/eva-mueller-kunstberatung\",\"https:\\\/\\\/www.youtube.com\\\/kunstberatungde\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kunst Im Treppenhaus - Eva Mueller Kunstberatung","description":"Die Kunstberaterin Eva Mueller hat ein Treppenhaus f\u00fcr die neuen Mieter im Gewerbegebiet in Breisach mit Kunst von Anna Thorwest gestaltet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/","og_locale":"de_DE","og_type":"article","og_title":"Kunst im Treppenhaus - Eva Mueller Kunstberatung","og_description":"Die Kunstberaterin Eva Mueller hat ein Treppenhaus f\u00fcr die neuen Mieter im Gewerbegebiet in Breisach mit Kunst von Anna Thorwest gestaltet","og_url":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/","og_site_name":"Eva Muellers Visionary Sunday Post","article_published_time":"2022-06-09T18:44:23+00:00","article_modified_time":"2022-07-15T14:51:41+00:00","og_image":[{"url":"https:\/\/i2.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwesteingang.133142.jpg","type":"","width":"","height":""}],"author":"Eva Mueller","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Eva Mueller","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/#article","isPartOf":{"@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/"},"author":{"name":"Eva Mueller","@id":"https:\/\/www.kunstberatung.de\/newsletter\/#\/schema\/person\/5956216e01d75d6ee2e332111165db0a"},"headline":"eva muellers visionary sunday post 638 &#8211; kunst im treppenhaus","datePublished":"2022-06-09T18:44:23+00:00","dateModified":"2022-07-15T14:51:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/"},"wordCount":430,"image":{"@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/#primaryimage"},"thumbnailUrl":"https:\/\/i2.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwesteingang.133142.jpg","articleSection":["Newsletter Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/","url":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/","name":"Kunst im Treppenhaus - Eva Mueller Kunstberatung","isPartOf":{"@id":"https:\/\/www.kunstberatung.de\/newsletter\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/#primaryimage"},"image":{"@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/#primaryimage"},"thumbnailUrl":"https:\/\/i2.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwesteingang.133142.jpg","datePublished":"2022-06-09T18:44:23+00:00","dateModified":"2022-07-15T14:51:41+00:00","author":{"@id":"https:\/\/www.kunstberatung.de\/newsletter\/#\/schema\/person\/5956216e01d75d6ee2e332111165db0a"},"description":"Die Kunstberaterin Eva Mueller hat ein Treppenhaus f\u00fcr die neuen Mieter im Gewerbegebiet in Breisach mit Kunst von Anna Thorwest gestaltet","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kunstberatung.de\/newsletter\/blog\/mutletter-638-kunst-im-treppenhaus\/#primaryimage","url":"https:\/\/i2.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwesteingang.133142.jpg","contentUrl":"https:\/\/i2.createsend1.com\/ei\/r\/19\/E85\/556\/csimport\/thorwesteingang.133142.jpg"},{"@type":"WebSite","@id":"https:\/\/www.kunstberatung.de\/newsletter\/#website","url":"https:\/\/www.kunstberatung.de\/newsletter\/","name":"Eva Muellers Visionary Sunday Post","description":"Eva Mueller Kunstberatung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kunstberatung.de\/newsletter\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.kunstberatung.de\/newsletter\/#\/schema\/person\/5956216e01d75d6ee2e332111165db0a","name":"Eva Mueller","sameAs":["https:\/\/www.kunstberatung.de","https:\/\/de.linkedin.com\/in\/eva-mueller-kunstberatung","https:\/\/www.youtube.com\/kunstberatungde"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/posts\/5783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/comments?post=5783"}],"version-history":[{"count":0,"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/posts\/5783\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/media?parent=5783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/categories?post=5783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kunstberatung.de\/newsletter\/wp-json\/wp\/v2\/tags?post=5783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}